{"id":1822,"date":"2021-10-08T14:46:53","date_gmt":"2021-10-08T21:46:53","guid":{"rendered":"https:\/\/news.venturacounty.gov\/?p=1822"},"modified":"2022-06-09T15:27:34","modified_gmt":"2022-06-09T22:27:34","slug":"new-director-of-airports-selected","status":"publish","type":"post","link":"https:\/\/news.venturacounty.gov\/es\/new-director-of-airports-selected\/","title":{"rendered":"Seleccionado Nuevo Director de Aeropuertos"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1822\" class=\"elementor elementor-1822\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a629d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a629d9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-70c960f\" data-id=\"70c960f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7de73d elementor-widget elementor-widget-text-editor\" data-id=\"a7de73d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\"><strong>Descargar art\u00edculo:<\/strong> <a title=\"Comunicado de prensa - Espanol\" href=\"https:\/\/vcportal.ventura.org\/CEO\/VCNC\/press_releases\/2021-10-08_vcnc_pr_new-airports-director-selected.pdf\" target=\"_blank\" rel=\"noopener\">Ingl\u00e9s<\/a> | <a title=\"Comunicado de prensa - Espa\u00f1ol\" href=\"https:\/\/vcportal.ventura.org\/CEO\/VCNC\/press_releases\/2021-10-08_vcnc_pr_new-airports-director-selected_sp.pdf\" target=\"_blank\" rel=\"noopener\">Espa\u00f1ol<\/a><\/p><p><img decoding=\"async\" style=\"width: 300px; margin-left: 20px;\" src=\"https:\/\/vcportal.ventura.org\/CEO\/VCNC\/press_releases\/2021-10-08_vcnc_pr_new-airports-director.jpg\" alt=\"Keith Freitas\" align=\"right\" \/>Ventura, CA \u2013 Keith Freitas ha sido seleccionado para dirigir los aeropuertos del Condado en Camarillo y Oxnard. El nombramiento como Director de Aeropuertos lo realiz\u00f3 Mike Powers, el Funcionario Ejecutivo del Condado. La selecci\u00f3n incluy\u00f3 una b\u00fasqueda a nivel nacional con 45 solicitantes y un panel de contrataci\u00f3n formado por miembros de la comunidad de la Autoridad Aeroportuaria de Camarillo y Oxnard, la Comisi\u00f3n Asesora de Aviaci\u00f3n, un representante del Consejo de Aeropuertos de California, as\u00ed como el Ayudante del Director Ejecutivo y Enlace Comunitario.<br \/><br \/>\u201cKeith aporta m\u00e1s de 30 a\u00f1os de experiencia combinada en gesti\u00f3n aeroportuaria. Tambi\u00e9n entiende la importancia de la participaci\u00f3n de la comunidad y en crear confianza con la comunidad\u201d, dijo el Funcionario Ejecutivo del Condado, Mike Powers. \u201cSu experiencia en el desarrollo de planes maestros y en reforzar la colaboraci\u00f3n y la comunicaci\u00f3n con todas las partes interesadas ser\u00e1 beneficiosa para nuestros aeropuertos y los miembros de nuestra comunidad.\u201d<\/p><p>Keith ha prestado sus servicios en los aeropuertos Long Beach Municipal, Mineta San Jose International y del Condado de Contra Costa (Buchanan Field y Byron). Posee la designaci\u00f3n de Ejecutivo Acreditado de Aeropuertos de la Asociaci\u00f3n Estadounidense de Ejecutivos de Aeropuertos, as\u00ed como los certificados de Piloto Privado y de Piloto Remoto de la FAA. Keith aporta experiencia en difusi\u00f3n comunitaria, al haber dirigido un proceso de Plan Maestro en Contra Costa, que incluy\u00f3 m\u00e1s de 22 reuniones comunitarias y concluy\u00f3 con un fuerte apoyo de la Junta y de la comunidad.<\/p><p>\u201cEstoy extremadamente emocionado y agradecido por la oportunidad de ayudar a dirigir los Aeropuertos del Condado de Ventura. Los Aeropuertos de Camarillo y Oxnard son activos valios\u00edsimos para todo el Condado de Ventura, y estoy deseoso de colaborar con miembros de la comunidad, pilotos, las ciudades de Camarillo y Oxnard, y las empresas aeroportuarias, para desarrollar una visi\u00f3n para estas instalaciones,\u201d dijo Keith Freitas.<\/p><p>Keith comenzar\u00e1 en su nuevo puesto al servicio de nuestra comunidad el 8 de noviembre de 2021.<\/p><p>Para saber m\u00e1s sobre los aeropuertos, por favor, visiten la p\u00e1gina <a title=\"Sitio web de los aeropuertos del condado de Ventura\" href=\"https:\/\/www.ventura.org\/airports\/\" target=\"_blank\" rel=\"noopener\">www.ventura.org\/aeropuertos\/<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Download article: English | En espa\u00f1ol Ventura, CA \u2013 Keith Freitas has been selected to run the County\u2019s airports in Camarillo and Oxnard. The appointment as Director of Airports was [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1754,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mo_disable_npp":"","footnotes":""},"categories":[33,6],"tags":[],"class_list":["post-1822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-airport","category-news"],"_links":{"self":[{"href":"https:\/\/news.venturacounty.gov\/es\/wp-json\/wp\/v2\/posts\/1822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.venturacounty.gov\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.venturacounty.gov\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.venturacounty.gov\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/news.venturacounty.gov\/es\/wp-json\/wp\/v2\/comments?post=1822"}],"version-history":[{"count":0,"href":"https:\/\/news.venturacounty.gov\/es\/wp-json\/wp\/v2\/posts\/1822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.venturacounty.gov\/es\/wp-json\/wp\/v2\/media\/1754"}],"wp:attachment":[{"href":"https:\/\/news.venturacounty.gov\/es\/wp-json\/wp\/v2\/media?parent=1822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.venturacounty.gov\/es\/wp-json\/wp\/v2\/categories?post=1822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.venturacounty.gov\/es\/wp-json\/wp\/v2\/tags?post=1822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}